{"id":10014,"date":"2025-11-11T01:48:57","date_gmt":"2025-11-11T04:48:57","guid":{"rendered":"https:\/\/dronefriendly.com.br\/v01\/?p=10014"},"modified":"2025-11-11T23:45:48","modified_gmt":"2025-11-12T02:45:48","slug":"dji-avata-360","status":"publish","type":"post","link":"https:\/\/dronefriendly.com.br\/v01\/dji-avata-360\/","title":{"rendered":"DJI Avata 360"},"content":{"rendered":"\n<h4 class=\"wp-block-heading\">O drone panor\u00e2mico da DJI chegou! Chamado DJI AVATA 360, com detec\u00e7\u00e3o omnidirecional de obst\u00e1culos. De acordo com uma reportagem recente do ve\u00edculo de m\u00eddia estrangeiro, o drone panor\u00e2mico da DJI foi finalizado e seu lan\u00e7amento no mercado foi confirmado.<\/h4>\n\n\n\n<p>Recentemente, imagens reais do drone panor\u00e2mico da DJI tamb\u00e9m circularam nas redes sociais. Com base nas imagens vazadas, o drone panor\u00e2mico da DJI se chama DJI AVATA 360 e suporta os modos de controle remoto e controle por movimento. Combinado com o ecossistema DJI, ele permite movimentos precisos da c\u00e2mera e voos imersivos.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/dronefriendly.com.br\/v01\/wp-content\/uploads\/2025\/11\/0065TFZ2ly1i783tl8m54j30go0b4ael.jpg\" alt=\"\" class=\"wp-image-10017\" srcset=\"https:\/\/dronefriendly.com.br\/v01\/wp-content\/uploads\/2025\/11\/0065TFZ2ly1i783tl8m54j30go0b4ael.jpg 600w, https:\/\/dronefriendly.com.br\/v01\/wp-content\/uploads\/2025\/11\/0065TFZ2ly1i783tl8m54j30go0b4ael-300x200.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n\n\n<p>Em termos de controle, o DJI AVATA 360 suporta os modos de controle remoto e controle por movimento. Os usu\u00e1rios podem desfrutar de voos panor\u00e2micos imersivos atrav\u00e9s de \u00f3culos de voo e joysticks, e tamb\u00e9m podem realizar movimentos de c\u00e2mera criativos mais eficientes e precisos com o controle remoto com tela.<\/p>\n\n\n<div class=\"wp-block-image is-style-default\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"395\" src=\"https:\/\/dronefriendly.com.br\/v01\/wp-content\/uploads\/2025\/11\/267915491c76df4.png\" alt=\"\" class=\"wp-image-10029\" srcset=\"https:\/\/dronefriendly.com.br\/v01\/wp-content\/uploads\/2025\/11\/267915491c76df4.png 600w, https:\/\/dronefriendly.com.br\/v01\/wp-content\/uploads\/2025\/11\/267915491c76df4-300x198.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n\n\n<p>Al\u00e9m de apresentar a prote\u00e7\u00e3o total das h\u00e9lices e um design omnidirecional de desvio de obst\u00e1culos que melhoram significativamente a seguran\u00e7a durante o rastreamento de movimento, o modo panor\u00e2mico de 360\u00b0 pode alternar para um modo de lente \u00fanica, equilibrando criatividade e qualidade de imagem em ambos os modos.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"399\" src=\"https:\/\/dronefriendly.com.br\/v01\/wp-content\/uploads\/2025\/11\/0065TFZ2ly1i783to0kvgj30go0b30z8.jpg\" alt=\"\" class=\"wp-image-10018\" srcset=\"https:\/\/dronefriendly.com.br\/v01\/wp-content\/uploads\/2025\/11\/0065TFZ2ly1i783to0kvgj30go0b30z8.jpg 600w, https:\/\/dronefriendly.com.br\/v01\/wp-content\/uploads\/2025\/11\/0065TFZ2ly1i783to0kvgj30go0b30z8-300x200.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n\n\n<p>Com base em vazamentos, o DJI AVATA 360 pode usar o mesmo sensor de 1 polegada da primeira c\u00e2mera panor\u00e2mica da DJI, a Osmo 360, oferecendo potencialmente recursos e qualidade de imagem de ponta. De acordo com as informa\u00e7\u00f5es vazadas sobre a configura\u00e7\u00e3o geral, muitos especialistas do setor especulam que a DJI n\u00e3o apenas tornou o produto mais poderoso, mas tamb\u00e9m pode oferecer um pre\u00e7o mais competitivo. Enquanto isso, as imagens reais vazadas podem indicar que o produto entrou na fase de prepara\u00e7\u00e3o para o lan\u00e7amento e deve ser lan\u00e7ado ainda este ano.<\/p>\n\n\n\n<p class=\"has-small-font-size\">Fonte: Rede social weibo (China)<\/p>\n\n\n\n<p><strong>Se gostou desta not\u00edcia, clique em qualquer an\u00fancio: voc\u00ea n\u00e3o paga nada por isso e o anunciante ajuda o nosso site com um centavinho de d\u00f3lar. <\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O drone panor\u00e2mico da DJI chegou! Chamado DJI AVATA 360, com detec\u00e7\u00e3o omnidirecional de obst\u00e1culos. De acordo com uma reportagem&hellip;<\/p>\n","protected":false},"author":1,"featured_media":10015,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"googlesitekit_rrm_CAowr_bfCw:productID":"","footnotes":""},"categories":[321,516,4,313],"tags":[638,9,395],"class_list":["post-10014","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque","category-lancamentos","category-noticias","category-paginas-negras","tag-dji-avata-360","tag-segredo","tag-vazamento"],"_links":{"self":[{"href":"https:\/\/dronefriendly.com.br\/v01\/wp-json\/wp\/v2\/posts\/10014","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dronefriendly.com.br\/v01\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dronefriendly.com.br\/v01\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dronefriendly.com.br\/v01\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dronefriendly.com.br\/v01\/wp-json\/wp\/v2\/comments?post=10014"}],"version-history":[{"count":9,"href":"https:\/\/dronefriendly.com.br\/v01\/wp-json\/wp\/v2\/posts\/10014\/revisions"}],"predecessor-version":[{"id":10032,"href":"https:\/\/dronefriendly.com.br\/v01\/wp-json\/wp\/v2\/posts\/10014\/revisions\/10032"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dronefriendly.com.br\/v01\/wp-json\/wp\/v2\/media\/10015"}],"wp:attachment":[{"href":"https:\/\/dronefriendly.com.br\/v01\/wp-json\/wp\/v2\/media?parent=10014"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dronefriendly.com.br\/v01\/wp-json\/wp\/v2\/categories?post=10014"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dronefriendly.com.br\/v01\/wp-json\/wp\/v2\/tags?post=10014"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}