{"id":151,"date":"2019-02-05T00:25:35","date_gmt":"2019-02-05T02:25:35","guid":{"rendered":"https:\/\/dronefriendly.com.br\/v01\/?p=151"},"modified":"2019-02-23T16:20:06","modified_gmt":"2019-02-23T18:20:06","slug":"decea-cria-bloqueio-para-operacao-de-drones-em-brumadinho-mg","status":"publish","type":"post","link":"https:\/\/dronefriendly.com.br\/v01\/decea-cria-bloqueio-para-operacao-de-drones-em-brumadinho-mg\/","title":{"rendered":"DECEA cria bloqueio para opera\u00e7\u00e3o de drones em Brumadinho-MG"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\"><strong>A medida foi necess\u00e1ria devido \u00e0 ocorr\u00eancia de voos irregulares no local <\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Contando com a colabora\u00e7\u00e3o de fabricantes de drones, o Departamento de  Controle do Espa\u00e7o A\u00e9reo (DECEA) estabeleceu uma \u00e1rea de restri\u00e7\u00e3o ao  voo de drone, chamada de <em>No Fly Zone<\/em> (NFZ), nas imedia\u00e7\u00f5es da  \u00e1rea afetada pelo desastre da Vale, em Brumadinho-MG.Pilotos remotos  realizaram opera\u00e7\u00f5es n\u00e3o autorizadas no local, desrespeitando os avisos  de proibi\u00e7\u00e3o de voos n\u00e3o coordenados. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\n\u201cV\u00e1rios pilotos se deslocaram para a \u00e1rea de Brumadinho logo no in\u00edcio \ndas atividades. O DECEA, por meio de m\u00eddias sociais, solicitou que \naqueles que l\u00e1 estivessem se dirigissem ao Centro de Controle, a fim de \nserem cadastrados e receberem as orienta\u00e7\u00f5es necess\u00e1rias para uma a\u00e7\u00e3o \ncoordenada e segura. Todos os volunt\u00e1rios que atenderam ao solicitado, \nreceberam as orienta\u00e7\u00f5es necess\u00e1rias e um trabalho coordenado foi \nrealizado, o que facilitou bastante algumas opera\u00e7\u00f5es\u201d, esclareceu o \nCoronel Aviador Jorge Humberto Vargas Rainho. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\nOpera\u00e7\u00f5es n\u00e3o autorizadas, realizadas por pilotos que n\u00e3o observaram as \nrestri\u00e7\u00f5es, as quais foram amplamente divulgadas pelos \u00f3rg\u00e3os de \nImprensa, colocaram em risco as aeronaves e o pessoal envolvido na \nopera\u00e7\u00e3o. Em sua maioria foram opera\u00e7\u00f5es realizadas por pilotos que \npretendiam comercializar as imagens posteriormente, ocorrendo a pris\u00e3o \nde dois autores das contraven\u00e7\u00f5es previstas nos Artigos 33 (dirigir \naeronave sem estar devidamente licenciado) e 35 (entregar-se na pr\u00e1tica \nda avia\u00e7\u00e3o, a acrobacias ou a voos baixos, fora da zona em que a lei o \npermita), ambos da Lei das Contraven\u00e7\u00f5es Penais. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\nNo local tamb\u00e9m foi instalado um equipamento capaz de detectar drones \ninvasores, o qual consegue localizar os dados da aeronave e a \nlocaliza\u00e7\u00e3o dos pilotos, que auxiliou nas pris\u00f5es. Al\u00e9m disso, as a\u00e7\u00f5es \nadministrativas internas, previstas na <a href=\"http:\/\/www.planalto.gov.br\/ccivil_03\/LEIS\/L7565.htm\" target=\"_blank\" rel=\"noopener\">Lei 7.565 \u2013 C\u00f3digo Brasileiro de Aeron\u00e1utica (CBA)<\/a>, ser\u00e3o tomadas pelo DECEA, assim que for notificado oficialmente pelas autoridades competentes. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\nO DECEA tamb\u00e9m refor\u00e7a que os drones s\u00e3o considerados pela legisla\u00e7\u00e3o \ncomo aeronaves e devem seguir as normas em vigor que s\u00e3o a <a href=\"https:\/\/publicacoes.decea.gov.br\/?i=publicacao&amp;id=4510\" target=\"_blank\" rel=\"noopener\">ICA 100-40 do DECEA<\/a> e o <a href=\"http:\/\/www.anac.gov.br\/assuntos\/legislacao\/legislacao-1\/rbha-e-rbac\/rbac\/rbac-e-94-emd-00\/@@display-file\/arquivo_norma\/RBACE94EMD00.pdf\" target=\"_blank\" rel=\"noopener\">RBAC-E 94 da ANAC<\/a>. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\n\u201c\u00c9 muito importante que os usu\u00e1rios entendam que as opera\u00e7\u00f5es n\u00e3o \nautorizadas colocam em risco as aeronaves tripuladas envolvidas e a \nopera\u00e7\u00e3o, inclusive com a possibilidade de termos novas v\u00edtimas, caso \nsejam acessadas \u00e1reas de risco. Por isso, a grande import\u00e2ncia de todas \nas a\u00e7\u00f5es serem coordenadas e autorizadas\u201d, complementa o Coronel Vargas.\n <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fonte: DECEA <\/p>\n","protected":false},"excerpt":{"rendered":"<p>A medida foi necess\u00e1ria devido \u00e0 ocorr\u00eancia de voos irregulares no local Contando com a colabora\u00e7\u00e3o de fabricantes de drones,&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"googlesitekit_rrm_CAowr_bfCw:productID":"","footnotes":""},"categories":[4],"tags":[15,17],"class_list":["post-151","post","type-post","status-publish","format-standard","hentry","category-noticias","tag-decea","tag-legislacao"],"_links":{"self":[{"href":"https:\/\/dronefriendly.com.br\/v01\/wp-json\/wp\/v2\/posts\/151","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dronefriendly.com.br\/v01\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dronefriendly.com.br\/v01\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dronefriendly.com.br\/v01\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dronefriendly.com.br\/v01\/wp-json\/wp\/v2\/comments?post=151"}],"version-history":[{"count":5,"href":"https:\/\/dronefriendly.com.br\/v01\/wp-json\/wp\/v2\/posts\/151\/revisions"}],"predecessor-version":[{"id":520,"href":"https:\/\/dronefriendly.com.br\/v01\/wp-json\/wp\/v2\/posts\/151\/revisions\/520"}],"wp:attachment":[{"href":"https:\/\/dronefriendly.com.br\/v01\/wp-json\/wp\/v2\/media?parent=151"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dronefriendly.com.br\/v01\/wp-json\/wp\/v2\/categories?post=151"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dronefriendly.com.br\/v01\/wp-json\/wp\/v2\/tags?post=151"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}