{"id":9941,"date":"2025-09-21T02:20:36","date_gmt":"2025-09-21T05:20:36","guid":{"rendered":"https:\/\/dronefriendly.com.br\/v01\/?p=9941"},"modified":"2025-09-21T02:26:44","modified_gmt":"2025-09-21T05:26:44","slug":"fotos-de-espionagem-seria-um-novo-drone-360","status":"publish","type":"post","link":"https:\/\/dronefriendly.com.br\/v01\/fotos-de-espionagem-seria-um-novo-drone-360\/","title":{"rendered":"Fotos de espionagem: Seria um drone DJI 360?"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">Algum tempo atr\u00e1s, tivemos uma not\u00edcia de uma pessoa de um grupo do WeChat (talvez, de dentro da DJI) sobre um novo drone FPV com fuselagem e design pr\u00f3ximo ao Avata 2, que ir\u00e1 competir diretamente com o recentemente (quase) lan\u00e7ado <a rel=\"noreferrer noopener\" href=\"https:\/\/www.antigravity.tech\/br\" target=\"_blank\">Insta 360 Antigravity<\/a> estaria em fase de finaliza\u00e7\u00e3o de software. <\/h3>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"375\" height=\"600\" src=\"https:\/\/dronefriendly.com.br\/v01\/wp-content\/uploads\/2025\/09\/66a5f138-5d1b-4b26-a791-a9f668e270b0-375x600.jpg\" alt=\"\" class=\"wp-image-9943\" srcset=\"https:\/\/dronefriendly.com.br\/v01\/wp-content\/uploads\/2025\/09\/66a5f138-5d1b-4b26-a791-a9f668e270b0-375x600.jpg 375w, https:\/\/dronefriendly.com.br\/v01\/wp-content\/uploads\/2025\/09\/66a5f138-5d1b-4b26-a791-a9f668e270b0-188x300.jpg 188w, https:\/\/dronefriendly.com.br\/v01\/wp-content\/uploads\/2025\/09\/66a5f138-5d1b-4b26-a791-a9f668e270b0-768x1229.jpg 768w, https:\/\/dronefriendly.com.br\/v01\/wp-content\/uploads\/2025\/09\/66a5f138-5d1b-4b26-a791-a9f668e270b0-960x1536.jpg 960w, https:\/\/dronefriendly.com.br\/v01\/wp-content\/uploads\/2025\/09\/66a5f138-5d1b-4b26-a791-a9f668e270b0.jpg 1000w\" sizes=\"auto, (max-width: 375px) 100vw, 375px\" \/><\/figure>\n<\/div>\n\n\n<p>Tradu\u00e7\u00e3o:<\/p>\n\n\n\n<p class=\"has-small-font-size\"><strong>Exclusivo | DJI incuba secretamente drone panor\u00e2mico, com lan\u00e7amento previsto para o final do ano<\/strong><\/p>\n\n\n\n<p class=\"has-small-font-size\">Informando com exclusividade que a DJI est\u00e1 secretamente desenvolvendo um drone panor\u00e2mico. O modelo foi aprimorado e v\u00e1rios sistemas de software est\u00e3o sendo depurados. O lan\u00e7amento oficial est\u00e1 previsto para o final do ano.<\/p>\n\n\n\n<p class=\"has-small-font-size\">Fontes revelaram que este drone panor\u00e2mico \u00e9 na verdade uma combina\u00e7\u00e3o integrada da c\u00e2mera panor\u00e2mica Osmo 360 lan\u00e7ada recentemente e de drones DJI anteriores, e a parte principal do drone \u00e9 provavelmente uma modifica\u00e7\u00e3o s\u00e9rie Mini.<\/p>\n\n\n\n<p class=\"has-small-font-size\">Anteriormente, a Insta 360 anunciou sua entrada no mercado de drones, adotando uma estrat\u00e9gia de marca dupla. Uma das marcas \u00e9 um drone panor\u00e2mico, desenvolvido principalmente em coopera\u00e7\u00e3o com terceiros; a outra \u00e9 a c\u00e2mera voadora HOVER. O produto \u00e9 comparado ao DJI Flip e se posiciona como um dispositivo de grava\u00e7\u00e3o de vlogs de n\u00edvel b\u00e1sico..<\/p>\n\n\n\n<p class=\"has-small-font-size\">Atualmente, os dois lados iniciaram uma competi\u00e7\u00e3o acirrada em c\u00e2meras panor\u00e2micas. Ap\u00f3s o lan\u00e7amento da c\u00e2mera panor\u00e2mica Osmo 360 da DJI, a Insta 360 imediatamente lan\u00e7ou uma promo\u00e7\u00e3o de redu\u00e7\u00e3o de pre\u00e7o para a s\u00e9rie X5, tanto na China quanto no exterior.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p>Diante das informa\u00e7\u00f5es acima, pens\u00e1vamos se tratar apenas de especula\u00e7\u00e3o ou &#8220;bal\u00e3o de ensaio&#8221; da pr\u00f3pria DJI, por\u00e9m come\u00e7aram a chegar essas imagens:<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"598\" src=\"https:\/\/dronefriendly.com.br\/v01\/wp-content\/uploads\/2025\/09\/result_01-800x598.png\" alt=\"\" class=\"wp-image-9945\" srcset=\"https:\/\/dronefriendly.com.br\/v01\/wp-content\/uploads\/2025\/09\/result_01-800x598.png 800w, https:\/\/dronefriendly.com.br\/v01\/wp-content\/uploads\/2025\/09\/result_01-300x224.png 300w, https:\/\/dronefriendly.com.br\/v01\/wp-content\/uploads\/2025\/09\/result_01-768x575.png 768w, https:\/\/dronefriendly.com.br\/v01\/wp-content\/uploads\/2025\/09\/result_01-160x120.png 160w, https:\/\/dronefriendly.com.br\/v01\/wp-content\/uploads\/2025\/09\/result_01.png 1024w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n<\/div>\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"598\" src=\"https:\/\/dronefriendly.com.br\/v01\/wp-content\/uploads\/2025\/09\/wmremove-transformed-800x598.jpeg\" alt=\"\" class=\"wp-image-9949\" srcset=\"https:\/\/dronefriendly.com.br\/v01\/wp-content\/uploads\/2025\/09\/wmremove-transformed-800x598.jpeg 800w, https:\/\/dronefriendly.com.br\/v01\/wp-content\/uploads\/2025\/09\/wmremove-transformed-300x224.jpeg 300w, https:\/\/dronefriendly.com.br\/v01\/wp-content\/uploads\/2025\/09\/wmremove-transformed-768x574.jpeg 768w, https:\/\/dronefriendly.com.br\/v01\/wp-content\/uploads\/2025\/09\/wmremove-transformed-160x120.jpeg 160w, https:\/\/dronefriendly.com.br\/v01\/wp-content\/uploads\/2025\/09\/wmremove-transformed.jpeg 1080w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n<\/div>\n\n\n<p>&#8230; Onde podemos ver claramente o logotipo da DJI e conforme aquela informa\u00e7\u00e3o chinesa, com fuselagem semelhante aos modelos que a DJI j\u00e1 produz e com uma grande diferen\u00e7a: uma enorme lente grande angular semelhante ao Antigravity A1 na parte superior, que seguramente deve possuir outra lente semelhante na parte de baixo.<\/p>\n\n\n\n<p>E tem outra foto, essa mais intrigante: <\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"544\" height=\"477\" src=\"https:\/\/dronefriendly.com.br\/v01\/wp-content\/uploads\/2025\/09\/b957f436-c795-438c-a49f-da649d642314.png\" alt=\"\" class=\"wp-image-9947\" srcset=\"https:\/\/dronefriendly.com.br\/v01\/wp-content\/uploads\/2025\/09\/b957f436-c795-438c-a49f-da649d642314.png 544w, https:\/\/dronefriendly.com.br\/v01\/wp-content\/uploads\/2025\/09\/b957f436-c795-438c-a49f-da649d642314-300x263.png 300w\" sizes=\"auto, (max-width: 544px) 100vw, 544px\" \/><\/figure>\n<\/div>\n\n\n<p>Talvez podemos prever para o final do ano um drone FPV DJI 360 com sensor LiDAR: Seria o m\u00e1ximo em imers\u00e3o e elevaria o FPV a outro n\u00edvel!<\/p>\n\n\n\n<p>Por enquanto o que temos, s\u00e3o fotos de alguns testes, e como sabemos muitos desse prot\u00f3tipos s\u00e3o lan\u00e7ados, outros modificados ou esquecidos, mas vindo da DJI s\u00e3o grandes as chances de n\u00e3o serem not\u00edcias de car\u00e1ter especulativo. <\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-small-font-size\">Fonte: meu jur\u00eddico me orientou a n\u00e3o divulgar, a menos que o dono das imagens se pronuncie. <\/p>\n\n\n\n<p>Gostou do post? Que tal clicar nos anunciantes? \u00c9 de gra\u00e7a e ajuda a manter o site &#8220;vivo&#8221;. <\/p>\n\n\n\n<script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-6902816207268885\"\n     crossorigin=\"anonymous\"><\/script>\n<ins class=\"adsbygoogle\"\n     style=\"display:block\"\n     data-ad-format=\"fluid\"\n     data-ad-layout-key=\"-f3-2e+bo-lc-4h\"\n     data-ad-client=\"ca-pub-6902816207268885\"\n     data-ad-slot=\"9111889444\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script>\n","protected":false},"excerpt":{"rendered":"<p>Algum tempo atr\u00e1s, tivemos uma not\u00edcia de uma pessoa de um grupo do WeChat (talvez, de dentro da DJI) sobre&hellip;<\/p>\n","protected":false},"author":1,"featured_media":9950,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"googlesitekit_rrm_CAowr_bfCw:productID":"","footnotes":""},"categories":[5,321,4,313],"tags":[633,632,9,395],"class_list":["post-9941","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigos","category-destaque","category-noticias","category-paginas-negras","tag-avata-360","tag-dji-360","tag-segredo","tag-vazamento"],"_links":{"self":[{"href":"https:\/\/dronefriendly.com.br\/v01\/wp-json\/wp\/v2\/posts\/9941","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dronefriendly.com.br\/v01\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dronefriendly.com.br\/v01\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dronefriendly.com.br\/v01\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dronefriendly.com.br\/v01\/wp-json\/wp\/v2\/comments?post=9941"}],"version-history":[{"count":9,"href":"https:\/\/dronefriendly.com.br\/v01\/wp-json\/wp\/v2\/posts\/9941\/revisions"}],"predecessor-version":[{"id":9959,"href":"https:\/\/dronefriendly.com.br\/v01\/wp-json\/wp\/v2\/posts\/9941\/revisions\/9959"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dronefriendly.com.br\/v01\/wp-json\/wp\/v2\/media\/9950"}],"wp:attachment":[{"href":"https:\/\/dronefriendly.com.br\/v01\/wp-json\/wp\/v2\/media?parent=9941"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dronefriendly.com.br\/v01\/wp-json\/wp\/v2\/categories?post=9941"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dronefriendly.com.br\/v01\/wp-json\/wp\/v2\/tags?post=9941"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}